{"id":22213,"date":"2020-06-25T13:55:57","date_gmt":"2020-06-25T11:55:57","guid":{"rendered":"https:\/\/www.uxban.com\/blog\/?p=11296"},"modified":"2020-10-26T12:08:42","modified_gmt":"2020-10-26T11:08:42","slug":"decoracion-de-interiores","status":"publish","type":"post","link":"https:\/\/www.uxban.com\/es\/2020\/06\/25\/decoracion-de-interiores\/","title":{"rendered":"Decoraci\u00f3n de interiores"},"content":{"rendered":"<p>Las tendencias en decoraci\u00f3n de interiores se renuevan a\u00f1o tras a\u00f1o y es en los espacios peque\u00f1os donde cobran m\u00e1s protagonismo que nunca. Las casas m\u00e1s modernas son ahora m\u00e1s naturales que nunca, con espacios modulables, armarios funcionales y colores que acent\u00faan la personalidad del interior de nuestro hogar.<\/p>\n<p>Aqu\u00ed os dejamos algunas ideas para decorar interiores que marcan tendencia.<\/p>\n<h2>Boa Mistura<\/h2>\n<p>Se dice de la buena mezcla y es justo lo que esta tendencia defiende. Se acabaron las paredes, suelos y rodapi\u00e9s con el mismo acabado e incluso color. Los pavimentos de cemento conviven con paredes de azulejos y cenefas que recuerdan y nos llevan al siglo pasado. Las paredes ya no est\u00e1n solo pintadas conviven con papeles pintados y texturas que dotan de personalidad \u00fanica cada estancia. Los tonos neutros siguen reinando pero los textiles y detalles especiales brillan con colores intensos y retadores.<\/p>\n<p><a href=\"http:\/\/www.uxban.com\/wp-content\/uploads\/2020\/10\/296.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11297\" alt=\"296\" src=\"http:\/\/www.uxban.com\/wp-content\/uploads\/2020\/10\/296.jpg\" width=\"1920\" height=\"1280\" \/><\/a><\/p>\n<h2>Pura Piedra<\/h2>\n<p>Los tonos naturales siguen estando presentes pero los que cobran protagonismo son los materiales naturales (m\u00e1rmol, piedra, pizarra, etc) que est\u00e1n presentes en suelos, paredes y paneles y en elementos como mesa de comedor o de centro, cocinas o detalles en ba\u00f1os<br \/>\nEstas texturas dan personalidad y crean espacios elegantes y de muy buen gusto.<\/p>\n<h2>L\u00e1mparas con luz y estilo<\/h2>\n<p>Apostar por l\u00e1mparas es una de las mejores tendencias en decoraci\u00f3n interior a seguir. Recuerda, adem\u00e1s de dar luz pueden crear una escenograf\u00eda \u00fanica. Formas geom\u00e9tricas, tama\u00f1os extraordinarios y juegos de luces al alcance de todos.<\/p>\n<p><a href=\"http:\/\/www.uxban.com\/wp-content\/uploads\/2020\/10\/22843.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11298\" alt=\"Lit lightbulb in the dark room\" src=\"http:\/\/www.uxban.com\/wp-content\/uploads\/2020\/10\/22843.jpg\" width=\"1920\" height=\"1280\" \/><\/a><\/p>\n<h2>Change, change y change<\/h2>\n<p>Los muebles de tendencia son modulables, multifuncionales y nos facilitan formas variadas de ser colocados, vividos y disfrutados.<\/p>\n<h2>Los 80 siempre vuelven<\/h2>\n<p>Colores ne\u00f3n, estampados geom\u00e9tricos, acabados cobre como sin\u00f3nimo de alegr\u00eda a raudales. En textiles, alfombras, muebles auxiliares, l\u00e1mparas o revestimientos. Una tendencia que ha venido para quedarse por una larga temporada.<\/p>\n<h2>M\u00e1s madera<\/h2>\n<p>La madera no es tendencia es un b\u00e1sico pero s\u00ed su forma de ser interpretada. El estilo n\u00f3rdico en tonos claros ha dado paso a muebles oscuros y profundos que reinterpretan los espacios y los convierten en espacios con car\u00e1cter e historias que contar. Colores vibrantes en piezas de muebles de madera oscura ser\u00e1n los reyes de muchas estancias de las casas m\u00e1s \u2018trendy\u2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las tendencias en decoraci\u00f3n de interiores se renuevan a\u00f1o tras a\u00f1o y es en los espacios peque\u00f1os donde cobran m\u00e1s protagonismo que nunca. Las casas m\u00e1s modernas son ahora m\u00e1s naturales que nunca, con espacios modulables, armarios funcionales y colores que acent\u00faan la personalidad del interior de nuestro hogar. Aqu\u00ed os dejamos algunas ideas para [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":22320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1637,12,18],"tags":[452,1498,30,60],"class_list":["post-22213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hogar-2","category-portada","category-interiorismo","tag-interiores","tag-suelos","tag-decoracion","tag-lamparas"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.uxban.com\/es\/wp-json\/wp\/v2\/posts\/22213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uxban.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uxban.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uxban.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uxban.com\/es\/wp-json\/wp\/v2\/comments?post=22213"}],"version-history":[{"count":1,"href":"https:\/\/www.uxban.com\/es\/wp-json\/wp\/v2\/posts\/22213\/revisions"}],"predecessor-version":[{"id":22322,"href":"https:\/\/www.uxban.com\/es\/wp-json\/wp\/v2\/posts\/22213\/revisions\/22322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uxban.com\/es\/wp-json\/wp\/v2\/media\/22320"}],"wp:attachment":[{"href":"https:\/\/www.uxban.com\/es\/wp-json\/wp\/v2\/media?parent=22213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uxban.com\/es\/wp-json\/wp\/v2\/categories?post=22213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uxban.com\/es\/wp-json\/wp\/v2\/tags?post=22213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}